{"id":1499,"date":"2018-10-24T21:15:25","date_gmt":"2018-10-24T19:15:25","guid":{"rendered":"http:\/\/kamblyco.cyon.link\/?post_type=products&#038;p=1499"},"modified":"2026-06-29T07:48:32","modified_gmt":"2026-06-29T05:48:32","slug":"eclats-de-noisettes","status":"publish","type":"products","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/","title":{"rendered":"\u00c9clats de Noisettes"},"template":"","products_type":[6,13,11],"class_list":["post-1499","products","type-products","status-publish","hentry","product-type-feingebaeck-kambly","product-type-mit-schokolade","product-type-mit-mandeln-nuesse"],"acf":[],"taxonomy-product-tag":false,"taxonomy-product-type":[6,13,11],"product-preview":{"image":{"ID":10447,"id":10447,"title":"Eclats_de_Noisettes_774x504","filename":"Eclats_de_Noisettes_774x504.jpg","filesize":54927,"url":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_774x504.jpg","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/eclats_de_noisettes_774x504\/","alt":"","author":"11","description":"","caption":"","name":"eclats_de_noisettes_774x504","status":"inherit","uploaded_to":1499,"date":"2024-01-30 14:32:20","modified":"2024-01-30 14:32:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/kambly.de\/wp\/wp-includes\/images\/media\/default.png","width":774,"height":504,"sizes":{"thumbnail":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_774x504-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_774x504-300x195.jpg","medium-width":300,"medium-height":195,"medium_large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_774x504-768x500.jpg","medium_large-width":768,"medium_large-height":500,"large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_774x504.jpg","large-width":774,"large-height":504,"1536x1536":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_774x504.jpg","1536x1536-width":774,"1536x1536-height":504,"2048x2048":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_774x504.jpg","2048x2048-width":774,"2048x2048-height":504}},"text":"Luftiges Schaumfeingeb\u00e4ck mit einer zarten Haselnuss-Cr\u00e8me und Schweizer Milchschokolade"},"product-heading":{"lead":"Eine liebevolle Kreation des Meister-Confiseurs, mit dem edlen Geschmack feinster Haseln\u00fcssen hoch drei: caramelisierte Haselnusssplitter auf knuspriger, luftiger Nussmeringue und zartschmelzender Haselnuss-Creme, spielerisch veredelt mit feinster Schweizer Milchschokolade. "},"image-slider":[{"image":{"ID":10448,"id":10448,"title":"Eclats_Noisettes_896x515","filename":"Eclats_Noisettes_896x515.jpg","filesize":68211,"url":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/eclats_noisettes_896x515\/","alt":"","author":"11","description":"","caption":"","name":"eclats_noisettes_896x515","status":"inherit","uploaded_to":1499,"date":"2024-01-30 14:32:40","modified":"2024-01-30 14:32:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/kambly.de\/wp\/wp-includes\/images\/media\/default.png","width":896,"height":515,"sizes":{"thumbnail":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515-300x172.jpg","medium-width":300,"medium-height":172,"medium_large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515-768x441.jpg","medium_large-width":768,"medium_large-height":441,"large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","large-width":896,"large-height":515,"1536x1536":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","1536x1536-width":896,"1536x1536-height":515,"2048x2048":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","2048x2048-width":896,"2048x2048-height":515}}},{"image":{"ID":10477,"id":10477,"title":"Eclats_de_Noisettes_100g_515","filename":"Eclats_de_Noisettes_100g_515.jpg","filesize":74309,"url":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/eclats_de_noisettes_100g_515\/","alt":"","author":"11","description":"","caption":"","name":"eclats_de_noisettes_100g_515","status":"inherit","uploaded_to":1499,"date":"2024-04-24 12:38:44","modified":"2024-04-24 12:38:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/kambly.de\/wp\/wp-includes\/images\/media\/default.png","width":896,"height":515,"sizes":{"thumbnail":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515-300x172.jpg","medium-width":300,"medium-height":172,"medium_large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515-768x441.jpg","medium_large-width":768,"medium_large-height":441,"large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","large-width":896,"large-height":515,"1536x1536":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","1536x1536-width":896,"1536x1536-height":515,"2048x2048":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","2048x2048-width":896,"2048x2048-height":515}}}],"product-images":{"image-slider":[{"image":{"ID":10448,"id":10448,"title":"Eclats_Noisettes_896x515","filename":"Eclats_Noisettes_896x515.jpg","filesize":68211,"url":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/eclats_noisettes_896x515\/","alt":"","author":"11","description":"","caption":"","name":"eclats_noisettes_896x515","status":"inherit","uploaded_to":1499,"date":"2024-01-30 14:32:40","modified":"2024-01-30 14:32:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/kambly.de\/wp\/wp-includes\/images\/media\/default.png","width":896,"height":515,"sizes":{"thumbnail":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515-300x172.jpg","medium-width":300,"medium-height":172,"medium_large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515-768x441.jpg","medium_large-width":768,"medium_large-height":441,"large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","large-width":896,"large-height":515,"1536x1536":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","1536x1536-width":896,"1536x1536-height":515,"2048x2048":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_Noisettes_896x515.jpg","2048x2048-width":896,"2048x2048-height":515}}},{"image":{"ID":10477,"id":10477,"title":"Eclats_de_Noisettes_100g_515","filename":"Eclats_de_Noisettes_100g_515.jpg","filesize":74309,"url":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/eclats_de_noisettes_100g_515\/","alt":"","author":"11","description":"","caption":"","name":"eclats_de_noisettes_100g_515","status":"inherit","uploaded_to":1499,"date":"2024-04-24 12:38:44","modified":"2024-04-24 12:38:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/kambly.de\/wp\/wp-includes\/images\/media\/default.png","width":896,"height":515,"sizes":{"thumbnail":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515-300x172.jpg","medium-width":300,"medium-height":172,"medium_large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515-768x441.jpg","medium_large-width":768,"medium_large-height":441,"large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","large-width":896,"large-height":515,"1536x1536":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","1536x1536-width":896,"1536x1536-height":515,"2048x2048":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_100g_515.jpg","2048x2048-width":896,"2048x2048-height":515}}}]},"product-informations":{"nutritions":[5264]},"product-history-slider-show":false,"products-chain-type":"none","products-chain-select":{"products-chain-type":"none"},"share":{"title":"\u00c9clats de Noisettes","text":"Luftiges Schaumfeingeb\u00e4ck mit einer zarten Haselnuss-Cr\u00e8me und Schweizer Milch-Chocolade","image":{"ID":10449,"id":10449,"title":"Eclats_de_Noisettes_1200x630","filename":"Eclats_de_Noisettes_1200x630.png","filesize":249743,"url":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630.png","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/eclats_de_noisettes_1200x630\/","alt":"","author":"11","description":"","caption":"","name":"eclats_de_noisettes_1200x630","status":"inherit","uploaded_to":1499,"date":"2024-01-30 14:33:01","modified":"2024-01-30 14:33:01","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/kambly.de\/wp\/wp-includes\/images\/media\/default.png","width":1200,"height":630,"sizes":{"thumbnail":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-300x158.png","medium-width":300,"medium-height":158,"medium_large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-768x403.png","medium_large-width":768,"medium_large-height":403,"large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-1024x538.png","large-width":1024,"large-height":538,"1536x1536":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630.png","1536x1536-width":1200,"1536x1536-height":630,"2048x2048":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630.png","2048x2048-width":1200,"2048x2048-height":630}},"keywords":"\u00c9clats de Noisettes, Biscuit, Feingeb\u00e4ck, Nussgeb\u00e4ck"},"overview-button-type-select":"sweet","product_tekrum":false,"product-recipes-show":false,"recipes-teaser-title":"","recipes-teaser-selection":"","recipes-teaser":{"recipes-teaser-title":"","recipes-teaser-selection":""},"seo":{"disallow_indexing":false,"":null,"share":{"title":"\u00c9clats de Noisettes","text":"Luftiges Schaumfeingeb\u00e4ck mit einer zarten Haselnuss-Cr\u00e8me und Schweizer Milch-Chocolade","image":{"ID":10449,"id":10449,"title":"Eclats_de_Noisettes_1200x630","filename":"Eclats_de_Noisettes_1200x630.png","filesize":249743,"url":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630.png","link":"https:\/\/kambly.de\/de\/product\/eclats-de-noisettes\/eclats_de_noisettes_1200x630\/","alt":"","author":"11","description":"","caption":"","name":"eclats_de_noisettes_1200x630","status":"inherit","uploaded_to":1499,"date":"2024-01-30 14:33:01","modified":"2024-01-30 14:33:01","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/kambly.de\/wp\/wp-includes\/images\/media\/default.png","width":1200,"height":630,"sizes":{"thumbnail":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-300x158.png","medium-width":300,"medium-height":158,"medium_large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-768x403.png","medium_large-width":768,"medium_large-height":403,"large":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630-1024x538.png","large-width":1024,"large-height":538,"1536x1536":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630.png","1536x1536-width":1200,"1536x1536-height":630,"2048x2048":"https:\/\/kambly.de\/app\/uploads\/2018\/10\/Eclats_de_Noisettes_1200x630.png","2048x2048-width":1200,"2048x2048-height":630}},"keywords":"\u00c9clats de Noisettes, Biscuit, Feingeb\u00e4ck, Nussgeb\u00e4ck"}},"product-buy":{"show":true,"label":"shop","link":{"title":"","url":"https:\/\/kambly.de\/de\/shop\/einzelpackungen\/eclats-de-noisettes-100-g","target":"_blank"}},"product-slider-show":false,"disallow_indexing":false,"article-content":false,"article":{"article-content":false},"_links":{"self":[{"href":"https:\/\/kambly.de\/de\/wp-json\/wp\/v2\/products\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kambly.de\/de\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/kambly.de\/de\/wp-json\/wp\/v2\/types\/products"}],"wp:attachment":[{"href":"https:\/\/kambly.de\/de\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"product-type","embeddable":true,"href":"https:\/\/kambly.de\/de\/wp-json\/wp\/v2\/products_type?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}